{"id":8578,"date":"2017-03-01T20:59:17","date_gmt":"2017-03-01T18:59:17","guid":{"rendered":"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/?p=8578"},"modified":"2017-03-01T21:06:18","modified_gmt":"2017-03-01T19:06:18","slug":"neugeborenenfotosession-fotodesign-jacqueline-schleicher","status":"publish","type":"post","link":"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/neugeborenenfotosession-fotodesign-jacqueline-schleicher\/","title":{"rendered":"Neugeborenenfotosession \/ Fotodesign Jacqueline Schleicher"},"content":{"rendered":"<p>Vor kurzem\u00a0hat diese frischgebackene\u00a0Familie unsere Fotografin Jacqueline Schleicher in ihrem Homestudio zwischen M\u00fcnchen und Augsburg besucht. Dabei ist eine wundervolle Mischung aus\u00a0Familien-, Geschwister- und Neugeborenenaufnahmen entstanden.<\/p>\n<p>Mehr von\u00a0Fotodesign Jacqueline Schleicher findet ihr unter: <a href=\"http:\/\/www.fotodesign-schleicher.de\">www.fotodesign-schleicher.de<\/a>\u00a0oder auf Facebook:\u00a0<a href=\"https:\/\/www.facebook.com\/fotodesign.jacqueline.schleicher\/\">https:\/\/www.facebook.com\/fotodesign.jacqueline.schleicher\/<\/a><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8580\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_2.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_2.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_2-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_2-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8594\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_16.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_16.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_16-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_16-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8579\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_1.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_1.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_1-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_1-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8582\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_4.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_4.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_4-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_4-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8581\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_3.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_3.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_3-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_3-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8583\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_5.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_5.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_5-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_5-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8593\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_15.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_15.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_15-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_15-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8592\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_14.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_14.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_14-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_14-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8591\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_13.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_13.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_13-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_13-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8588\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_10.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_10.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_10-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_10-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8587\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_9.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_9.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_9-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_9-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8589\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_11.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_11.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_11-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_11-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8586\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_8.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_8.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_8-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_8-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8585\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_7.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_7.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_7-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_7-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8584\" src=\"http:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_6.jpg\" alt=\"\" width=\"900\" height=\"616\" srcset=\"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_6.jpg 900w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_6-300x205.jpg 300w, https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-content\/uploads\/2017\/02\/28-8578-post\/Babyfotos_dachau_6-768x526.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor kurzem\u00a0hat diese frischgebackene\u00a0Familie unsere Fotografin Jacqueline Schleicher in ihrem Homestudio zwischen M\u00fcnchen und Augsburg besucht. Dabei ist eine wundervolle Mischung aus\u00a0Familien-, Geschwister- und Neugeborenenaufnahmen entstanden. Mehr von\u00a0Fotodesign Jacqueline Schleicher findet ihr unter: www.fotodesign-schleicher.de\u00a0oder auf Facebook:\u00a0https:\/\/www.facebook.com\/fotodesign.jacqueline.schleicher\/<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pp_embeds":""},"categories":[578,1],"tags":[12,83,117,354,61,890,82],"acf":[],"_links":{"self":[{"href":"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-json\/wp\/v2\/posts\/8578"}],"collection":[{"href":"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-json\/wp\/v2\/comments?post=8578"}],"version-history":[{"count":6,"href":"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-json\/wp\/v2\/posts\/8578\/revisions"}],"predecessor-version":[{"id":8600,"href":"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-json\/wp\/v2\/posts\/8578\/revisions\/8600"}],"wp:attachment":[{"href":"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-json\/wp\/v2\/media?parent=8578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-json\/wp\/v2\/categories?post=8578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vereinigung-professioneller-kinderfotografen.de\/blog2\/wp-json\/wp\/v2\/tags?post=8578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}